{"id":91,"count":12,"description":"","link":"https:\/\/equimedsv.com\/en\/product-category\/terapia-respiratoria\/","name":"Terapia Respiratoria","slug":"terapia-respiratoria","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV<\/title>\n<meta name=\"description\" content=\"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/equimedsv.com\/en\/product-category\/terapia-respiratoria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV\" \/>\n<meta property=\"og:description\" content=\"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/equimedsv.com\/en\/product-category\/terapia-respiratoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Equimed El Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@equimedsv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/equimedsv.com\\\/product-category\\\/terapia-respiratoria\\\/\",\"url\":\"https:\\\/\\\/equimedsv.com\\\/product-category\\\/terapia-respiratoria\\\/\",\"name\":\"Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#website\"},\"description\":\"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/equimedsv.com\\\/product-category\\\/terapia-respiratoria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/equimedsv.com\\\/product-category\\\/terapia-respiratoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/equimedsv.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terapia Respiratoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#website\",\"url\":\"https:\\\/\\\/equimedsv.com\\\/\",\"name\":\"Equimed El Salvador\",\"description\":\"Distribuci\u00f3n, Venta y Reparaci\u00f3n de Equipos M\u00e9dicos y Hospitalario\",\"publisher\":{\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/equimedsv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#organization\",\"name\":\"Equimed El Salvador\",\"url\":\"https:\\\/\\\/equimedsv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/equimedsv.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-equimed-actual.png\",\"contentUrl\":\"https:\\\/\\\/equimedsv.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Logo-equimed-actual.png\",\"width\":3426,\"height\":731,\"caption\":\"Equimed El Salvador\"},\"image\":{\"@id\":\"https:\\\/\\\/equimedsv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/Equimedsv\\\/\",\"https:\\\/\\\/x.com\\\/equimedsv\",\"https:\\\/\\\/www.instagram.com\\\/equimed_sv\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV","description":"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/equimedsv.com\/en\/product-category\/terapia-respiratoria\/","og_locale":"en_US","og_type":"article","og_title":"Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV","og_description":"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.","og_url":"https:\/\/equimedsv.com\/en\/product-category\/terapia-respiratoria\/","og_site_name":"Equimed El Salvador","twitter_card":"summary_large_image","twitter_site":"@equimedsv","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/equimedsv.com\/product-category\/terapia-respiratoria\/","url":"https:\/\/equimedsv.com\/product-category\/terapia-respiratoria\/","name":"Terapia Respiratoria: Nebulizadores y Accesorios | EQUIMEDSV","isPartOf":{"@id":"https:\/\/equimedsv.com\/#website"},"description":"Encuentra nebulizadores de uso dom\u00e9stico y cl\u00ednico en EQUIMEDSV. Ideales para adultos y ni\u00f1os. F\u00e1cil uso, bajo ruido, entrega r\u00e1pida en todo El Salvador.","breadcrumb":{"@id":"https:\/\/equimedsv.com\/product-category\/terapia-respiratoria\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/equimedsv.com\/product-category\/terapia-respiratoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/equimedsv.com\/"},{"@type":"ListItem","position":2,"name":"Terapia Respiratoria"}]},{"@type":"WebSite","@id":"https:\/\/equimedsv.com\/#website","url":"https:\/\/equimedsv.com\/","name":"Equimed El Salvador","description":"Distribuci\u00f3n, Venta y Reparaci\u00f3n de Equipos M\u00e9dicos y Hospitalario","publisher":{"@id":"https:\/\/equimedsv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/equimedsv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/equimedsv.com\/#organization","name":"Equimed El Salvador","url":"https:\/\/equimedsv.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/equimedsv.com\/#\/schema\/logo\/image\/","url":"https:\/\/equimedsv.com\/wp-content\/uploads\/2021\/10\/Logo-equimed-actual.png","contentUrl":"https:\/\/equimedsv.com\/wp-content\/uploads\/2021\/10\/Logo-equimed-actual.png","width":3426,"height":731,"caption":"Equimed El Salvador"},"image":{"@id":"https:\/\/equimedsv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/Equimedsv\/","https:\/\/x.com\/equimedsv","https:\/\/www.instagram.com\/equimed_sv\/"]}]}},"_links":{"self":[{"href":"https:\/\/equimedsv.com\/en\/wp-json\/wp\/v2\/product_cat\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/equimedsv.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/equimedsv.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/equimedsv.com\/en\/wp-json\/wp\/v2\/product?product_cat=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}